{"id":130,"count":4,"description":"","link":"https:\/\/www.coollibri.de\/blog\/tag\/marketing\/","name":"marketing","slug":"marketing","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>marketing Archives - Coollibri.de<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.coollibri.de\/blog\/tag\/marketing\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"marketing Archives - Coollibri.de\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.coollibri.de\/blog\/tag\/marketing\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Coollibri.de\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/tag\\\/marketing\\\/\",\"url\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/tag\\\/marketing\\\/\",\"name\":\"marketing Archives - Coollibri.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/tag\\\/marketing\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/tag\\\/marketing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"marketing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/\",\"name\":\"Coollibri.de\",\"description\":\"Ich druch mein Buch\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/#organization\",\"name\":\"Coollibride\",\"url\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-coollibri.de_.png\",\"contentUrl\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-coollibri.de_.png\",\"width\":231,\"height\":72,\"caption\":\"Coollibride\"},\"image\":{\"@id\":\"https:\\\/\\\/www.coollibri.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"marketing Archives - Coollibri.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coollibri.de\/blog\/tag\/marketing\/","og_locale":"en_US","og_type":"article","og_title":"marketing Archives - Coollibri.de","og_url":"https:\/\/www.coollibri.de\/blog\/tag\/marketing\/","og_site_name":"Coollibri.de","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.coollibri.de\/blog\/tag\/marketing\/","url":"https:\/\/www.coollibri.de\/blog\/tag\/marketing\/","name":"marketing Archives - Coollibri.de","isPartOf":{"@id":"https:\/\/www.coollibri.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.coollibri.de\/blog\/tag\/marketing\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coollibri.de\/blog\/tag\/marketing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.coollibri.de\/blog\/"},{"@type":"ListItem","position":2,"name":"marketing"}]},{"@type":"WebSite","@id":"https:\/\/www.coollibri.de\/blog\/#website","url":"https:\/\/www.coollibri.de\/blog\/","name":"Coollibri.de","description":"Ich druch mein Buch","publisher":{"@id":"https:\/\/www.coollibri.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coollibri.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.coollibri.de\/blog\/#organization","name":"Coollibride","url":"https:\/\/www.coollibri.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.coollibri.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.coollibri.de\/blog\/wp-content\/uploads\/2023\/05\/logo-coollibri.de_.png","contentUrl":"https:\/\/www.coollibri.de\/blog\/wp-content\/uploads\/2023\/05\/logo-coollibri.de_.png","width":231,"height":72,"caption":"Coollibride"},"image":{"@id":"https:\/\/www.coollibri.de\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.coollibri.de\/blog\/wp-json\/wp\/v2\/tags\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coollibri.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.coollibri.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.coollibri.de\/blog\/wp-json\/wp\/v2\/posts?tags=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}